{"id":75,"date":"2016-12-14T16:01:52","date_gmt":"2016-12-14T16:01:52","guid":{"rendered":"http:\/\/onschedule.edge-themes.com\/?p=75"},"modified":"2020-07-31T17:30:53","modified_gmt":"2020-07-31T20:30:53","slug":"crise-como-o-empreendedor-pode-lidar-com-ela","status":"publish","type":"post","link":"https:\/\/www.oliconsultoria.com.br\/site\/2016\/12\/14\/crise-como-o-empreendedor-pode-lidar-com-ela\/","title":{"rendered":"Crise: como o empreendedor pode lidar com ela"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<em>Em tempos de coronav\u00edrus, os pequenos empreendedores t\u00eam sofrido as consequ\u00eancias dessa crise e a inova\u00e7\u00e3o \u00e9 pe\u00e7a fundamental para esse momento. <\/em>[\/vc_column_text][vc_empty_space height=&#8221;29px&#8221;][vc_column_text css=&#8221;.vc_custom_1485770112089{padding-right: 7% !important;}&#8221;]<\/p>\n<blockquote><p>While money can&#8217;t buy happiness, it certainly lets you choose your own form of misery<\/p>\n<p style=\"font-size: 14px; line-height: 40px; font-weight: 300;\">Groucho Marx<\/p>\n<\/blockquote>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;13px&#8221;][vc_column_text]Toda crise, como a que o vivemos agora com a pandemia do <a href=\"https:\/\/coronavirus.saude.gov.br\/sobre-a-doenca\">coronav\u00edrus<\/a>, representa uma amea\u00e7a para as empresas e empreendedores, mas pode ser tamb\u00e9m uma oportunidade de fazer diferente e descobrir novos caminhos.[\/vc_column_text][vc_empty_space height=&#8221;29px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column offset=&#8221;vc_col-lg-5 vc_col-md-12&#8243;][vc_empty_space height=&#8221;8px&#8221;][vc_single_image image=&#8221;5821&#8243; img_size=&#8221;full&#8221;][vc_empty_space height=&#8221;29px&#8221;][\/vc_column][vc_column offset=&#8221;vc_col-lg-7 vc_col-md-12 vc_col-xs-12&#8243;][vc_column_text]Diante de uma crise, muitas empresas focam em reduzir custos, mas, muitas vezes, a \u00fanica sa\u00edda est\u00e1 na criatividade.<\/p>\n<p>Para superar obst\u00e1culos, a inova\u00e7\u00e3o \u00e9 muito necess\u00e1ria, assim como saber contornar situa\u00e7\u00f5es e conseguir agregar valor para seus clientes, criando diferenciais.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][vc_column_text]Na economia moderna, a vantagem competitiva est\u00e1 naquelas empresas que conseguem ser mais \u00e1geis, e n\u00e3o exatamente as maiores. Ou seja, voc\u00ea n\u00e3o precisa ter uma grande empresa para inovar, a inova\u00e7\u00e3o pode ser um diferencial para os pequenos neg\u00f3cios.[\/vc_column_text][vc_empty_space height=&#8221;29px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h5><strong>Planejamento de a\u00e7\u00f5es para tomada de decis\u00f5es<\/strong><\/h5>\n<p>[\/vc_column_text][vc_column_text]Mas antes de tomar qualquer decis\u00e3o e agir, \u00e9 necess\u00e1rio que voc\u00ea reveja o seu planejamento estrat\u00e9gico. Al\u00e9m disso, deve avaliar seus objetivos e ver se eles est\u00e3o condizendo com a situa\u00e7\u00e3o atual da empresa e do mercado. Ap\u00f3s isso, deve fazer as modifica\u00e7\u00f5es que forem necess\u00e1rias.<\/p>\n<p>Se voc\u00ea quer (ou precisa) de resultados diferentes, deve agir de forma diferente. Ent\u00e3o, a revis\u00e3o do seu planejamento estrat\u00e9gico \u00e9 o primeiro passo para definir e alcan\u00e7ar novos objetivos.[\/vc_column_text][vc_column_text]Depois, \u00e9 importante avaliar o mercado e como a concorr\u00eancia est\u00e1 se comportando nesse tempo cr\u00edtico. Isso \u00e9 essencial para avaliar quais tem sido as pr\u00e1ticas que est\u00e3o funcionando. Al\u00e9m disso, \u00e9 importante analisar o comportamento dos clientes, se continua sendo o mesmo, o que eles esperam.[\/vc_column_text][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h5><strong>Exemplos de inova\u00e7\u00e3o em tempos de crise<\/strong><\/h5>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;29px&#8221;][vc_column_text]N\u00e3o pense que inova\u00e7\u00e3o se d\u00e1 apenas no uso de tecnologias de ponta como rob\u00f4s e nanotecnologia. O conceito de inova\u00e7\u00e3o vai muito al\u00e9m disso e n\u00e3o est\u00e1 restrito a alta tecnologia e grandes empresas.<\/p>\n<p>Ela \u00e9 aplicada nas empresas quando se consegue solu\u00e7\u00f5es para problemas espec\u00edficos e, nesse momento, s\u00e3o muitos os problemas que as empresas est\u00e3o enfrentando. Inovar pode at\u00e9 ser vender o mesmo produto ou servi\u00e7o de sempre, mas de uma forma diferente.[\/vc_column_text][vc_column_text]Ent\u00e3o vamos aos exemplos pr\u00e1ticos de como as empresas podem inovar durante esse tempo de crise de coronav\u00edrus?<\/p>\n<p>Primeiro, se voc\u00ea n\u00e3o tinha uma loja virtual ou p\u00e1ginas em redes sociais para vender seus produtos e servi\u00e7os, essa \u00e9 a primeira boa e funcional inova\u00e7\u00e3o a que deve aderir para garantir a continua\u00e7\u00e3o de suas vendas.<\/p>\n<p>Engana-se quem pensa que o servi\u00e7o de delivery \u00e9 apenas para restaurantes e lanchonetes. O servi\u00e7o de entrega em domic\u00edlio \u00e9 diversificado e abrange, agora mais do que nunca, variados tipos de estabelecimentos. Como, por exemplo, lojas de roupa, pet shops, farm\u00e1cias e etc. Assim voc\u00ea gera um novo espa\u00e7o no mercado e compensa a falta de vendas presenciais.[\/vc_column_text][vc_column_text]Por \u00faltimo, uma boa estrat\u00e9gia pode ser a capacita\u00e7\u00e3o. Tente utilizar algum tempo livre que tenha para adquirir novos conhecimentos e habilidades empreendedoras e de gest\u00e3o. Fa\u00e7a cursos online, assista a confer\u00eancias e tutoriais que ensinem t\u00e9cnicas de divulga\u00e7\u00e3o e se inspire em cases de sucesso.[\/vc_column_text][vc_empty_space height=&#8221;29px&#8221;][vc_column_text]Como mostramos ao longo desse texto, a inova\u00e7\u00e3o \u00e9 a sa\u00edda para os pequenos neg\u00f3cios driblarem a crise econ\u00f4mica causada pelo novo coronav\u00edrus.[\/vc_column_text][vc_column_text]Leia mais artigos:<\/p>\n<p class=\"entry-title edgtf-post-title\"><a href=\"https:\/\/www.oliconsultoria.com.br\/site\/2017\/01\/04\/mundo-dos-negocios-nos-proximos-tempos\/\">Mundo dos neg\u00f3cios nos pr\u00f3ximos tempos<\/a><\/p>\n<p><a href=\"https:\/\/www.oliconsultoria.com.br\/site\/2017\/01\/04\/8-vantagens-de-ter-uma-loja-virtual\/\">8 vantagens de ter uma loja virtual<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Map where your photos were taken and discover local points of interest map where your photos were. Lorem ipsum dolor siter Cum sociis natoque penatibus et magnis.<\/p>\n","protected":false},"author":1,"featured_media":8972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[42],"uagb_featured_image_src":{"full":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2.jpg",957,594,false],"thumbnail":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-150x150.jpg",150,150,true],"medium":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-300x186.jpg",300,186,true],"medium_large":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-768x477.jpg",768,477,true],"large":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2.jpg",957,594,false],"1536x1536":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2.jpg",957,594,false],"2048x2048":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2.jpg",957,594,false],"fluid_edge_image_square":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-550x550.jpg",550,550,true],"fluid_edge_image_landscape":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-957x550.jpg",957,550,true],"fluid_edge_image_portrait":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-550x594.jpg",550,594,true],"fluid_edge_image_huge":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2.jpg",957,594,false],"woocommerce_thumbnail":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-600x372.jpg",600,372,true],"woocommerce_gallery_thumbnail":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-100x100.jpg",100,100,true],"shop_catalog":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-300x300.jpg",300,300,true],"shop_single":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-600x372.jpg",600,372,true],"shop_thumbnail":["https:\/\/www.oliconsultoria.com.br\/site\/wp-content\/uploads\/2016\/12\/compra-online2-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"admineoliveira","author_link":"https:\/\/www.oliconsultoria.com.br\/site\/author\/admineoliveira\/"},"uagb_comment_info":0,"uagb_excerpt":"Map where your photos were taken and discover local points of interest map where your photos were. Lorem ipsum dolor siter Cum sociis natoque penatibus et magnis.","_links":{"self":[{"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/posts\/75"}],"collection":[{"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/comments?post=75"}],"version-history":[{"count":14,"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/posts\/75\/revisions"}],"predecessor-version":[{"id":8994,"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/posts\/75\/revisions\/8994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/media\/8972"}],"wp:attachment":[{"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/media?parent=75"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/categories?post=75"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oliconsultoria.com.br\/site\/wp-json\/wp\/v2\/tags?post=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}